{"id":914,"date":"2025-02-21T12:13:10","date_gmt":"2025-02-21T15:13:10","guid":{"rendered":"https:\/\/morrison.gob.ar\/?p=914"},"modified":"2025-02-21T12:13:11","modified_gmt":"2025-02-21T15:13:11","slug":"morrison-suma-nuevos-espacios-para-la-recreacion-y-el-deporte","status":"publish","type":"post","link":"https:\/\/morrison.gob.ar\/index.php\/2025\/02\/21\/morrison-suma-nuevos-espacios-para-la-recreacion-y-el-deporte\/","title":{"rendered":"Morrison suma nuevos espacios para la recreaci\u00f3n y el deporte."},"content":{"rendered":"\n<p>La Municipalidad de Morrison, a trav\u00e9s del \u00c1rea de Deportes y en colaboraci\u00f3n con diversas \u00e1reas municipales, avanza en la renovaci\u00f3n y acondicionamiento de espacios p\u00fablicos con el objetivo de fomentar la recreaci\u00f3n y la actividad f\u00edsica en la comunidad.<\/p>\n\n\n\n<p>En el sector Cura Brochero, se est\u00e1n construyendo nuevas canchas de tejo, pensadas especialmente para el disfrute de los adultos mayores. Esta iniciativa busca promover la integraci\u00f3n social, el bienestar f\u00edsico y la salud, reforzando el compromiso municipal con una mejor calidad de vida para todos los vecinos.<\/p>\n\n\n\n<p>\u00abEl deporte es una herramienta fundamental para la convivencia y el bienestar, por eso seguimos apostando a la recuperaci\u00f3n de espacios que permitan la participaci\u00f3n de toda la comunidad\u00bb, destacaron desde la Municipalidad.<\/p>\n\n\n\n<p>Se invita a los vecinos a disfrutar de estos nuevos espacios y a sumarse a las actividades que la Municipalidad pone a disposici\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"846\" height=\"1024\" data-id=\"918\" src=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/111-846x1024.jpg\" alt=\"\" class=\"wp-image-918\" srcset=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/111-846x1024.jpg 846w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/111-248x300.jpg 248w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/111-768x930.jpg 768w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/111-1269x1536.jpg 1269w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/111.jpg 1440w\" sizes=\"(max-width: 846px) 100vw, 846px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"846\" height=\"1024\" data-id=\"919\" src=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/222-846x1024.jpg\" alt=\"\" class=\"wp-image-919\" srcset=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/222-846x1024.jpg 846w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/222-248x300.jpg 248w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/222-768x930.jpg 768w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/222-1269x1536.jpg 1269w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/222.jpg 1440w\" sizes=\"(max-width: 846px) 100vw, 846px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"642\" data-id=\"916\" src=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/333.jpg\" alt=\"\" class=\"wp-image-916\" srcset=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/333.jpg 600w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/333-280x300.jpg 280w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"622\" data-id=\"917\" src=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/444.jpg\" alt=\"\" class=\"wp-image-917\" srcset=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/444.jpg 600w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/444-289x300.jpg 289w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"635\" data-id=\"915\" src=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/555.jpg\" alt=\"\" class=\"wp-image-915\" srcset=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/555.jpg 600w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/02\/555-283x300.jpg 283w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de Morrison, a trav\u00e9s del \u00c1rea de Deportes y en colaboraci\u00f3n con diversas \u00e1reas municipales, avanza en la renovaci\u00f3n y acondicionamiento de espacios p\u00fablicos con el objetivo de fomentar la recreaci\u00f3n y la actividad f\u00edsica en la comunidad. En el sector Cura Brochero, se est\u00e1n construyendo nuevas canchas de tejo, pensadas especialmente para&#8230;<\/p>\n","protected":false},"author":3,"featured_media":916,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/914"}],"collection":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=914"}],"version-history":[{"count":1,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/914\/revisions"}],"predecessor-version":[{"id":920,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/914\/revisions\/920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/916"}],"wp:attachment":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}