{"id":439,"date":"2024-07-02T20:36:48","date_gmt":"2024-07-02T23:36:48","guid":{"rendered":"https:\/\/morrison.gob.ar\/?p=439"},"modified":"2024-07-02T20:38:04","modified_gmt":"2024-07-02T23:38:04","slug":"cultura-noches-de-cine-y-solidaridad","status":"publish","type":"post","link":"https:\/\/morrison.gob.ar\/index.php\/2024\/07\/02\/cultura-noches-de-cine-y-solidaridad\/","title":{"rendered":"Cultura: Noches de cine y solidaridad"},"content":{"rendered":"\n<p>Desde el \u00e1rea de Cultura de la Municipalidad de Morrison se mostraron conformes y satisfechos por la importante afluencia de p\u00fablico, a las jornadas de cine solidario realizado en el Centro Cultural de Morrison.<\/p>\n\n\n\n<p>La entrada solicitada era un alimento perecedero y lo recaudado fue donado a La Fazenda de la Esperanza.<\/p>\n\n\n\n<p>Todo lo recaudado en el Kiosco es a total beneficio de las instituciones del medio.<\/p>\n\n\n\n<p>La responsable del \u00e1rea de cultura Isadora Rossa Rocha remarc\u00f3 que la iniciativa comenz\u00f3 con un proyecto conjunto entre la municipalidad y la emisora local FM Morrison.<\/p>\n\n\n\n<p>Desde el municipio agradecen &nbsp;a todos por sumarse a esta iniciativa.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"ISADORA ROSSA ROCHA   CINE CENTRO CULTURAL\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/1QEeZ4Ann5I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Desde el \u00e1rea de Cultura de la Municipalidad de Morrison se mostraron conformes y satisfechos por la importante afluencia de p\u00fablico, a las jornadas de cine solidario realizado en el Centro Cultural de Morrison. La entrada solicitada era un alimento perecedero y lo recaudado fue donado a La Fazenda de la Esperanza. Todo lo recaudado&#8230;<\/p>\n","protected":false},"author":3,"featured_media":441,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/439"}],"collection":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=439"}],"version-history":[{"count":1,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/439\/revisions"}],"predecessor-version":[{"id":440,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/439\/revisions\/440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/441"}],"wp:attachment":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}