{"id":1514,"date":"2026-01-21T08:22:46","date_gmt":"2026-01-21T11:22:46","guid":{"rendered":"https:\/\/morrison.gob.ar\/?p=1514"},"modified":"2026-01-21T17:46:53","modified_gmt":"2026-01-21T20:46:53","slug":"seguimos-comparti","status":"publish","type":"post","link":"https:\/\/morrison.gob.ar\/index.php\/2026\/01\/21\/seguimos-comparti\/","title":{"rendered":"M\u00e1s postales de  8\u00b0 Feria de Sabores del Mundo"},"content":{"rendered":"\n<p>En esta oportunidad, es el turno de los emprenddimientos gastron\u00f3micos, tanto locales como de otras localidades, que aportaron sabor, aroma y ese toque especial que hizo de esta feria una verdadera experiencia para todos los sentidos.<\/p>\n\n\n\n<p>Comidas, tragos y bebidas formaron parte de una propuesta variada y de gran calidad, que acompa\u00f1\u00f3 una jornada donde la cultura, la m\u00fasica y el encuentro fueron protagonistas.<\/p>\n\n\n\n<p>Desde la Municipalidad de Morrison y el Club Emprendedores, agradecemos a cada gastron\u00f3mico que particip\u00f3 y fue parte de este gran encuentro gastron\u00f3mico y cultural que sigue creciendo a\u00f1o a a\u00f1o.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2728\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tf4\/1\/16\/2728.png\"> Gracias por sumar su talento y su pasi\u00f3n.<\/p>\n\n\n\n<p>Seguimos impulsando el trabajo, la identidad y el desarrollo local.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"750\" data-id=\"1515\" src=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/000-1.jpg\" alt=\"\" class=\"wp-image-1515\" srcset=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/000-1.jpg 600w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/000-1-240x300.jpg 240w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"655\" data-id=\"1519\" src=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/222.jpg\" alt=\"\" class=\"wp-image-1519\" srcset=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/222.jpg 600w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/222-275x300.jpg 275w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"600\" data-id=\"1516\" src=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/333.jpg\" alt=\"\" class=\"wp-image-1516\" srcset=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/333.jpg 480w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/333-240x300.jpg 240w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"750\" data-id=\"1517\" src=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/444.jpg\" alt=\"\" class=\"wp-image-1517\" srcset=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/444.jpg 600w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/444-240x300.jpg 240w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"750\" data-id=\"1518\" src=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/555.jpg\" alt=\"\" class=\"wp-image-1518\" srcset=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/555.jpg 600w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/555-240x300.jpg 240w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"750\" data-id=\"1520\" src=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/666.jpg\" alt=\"\" class=\"wp-image-1520\" srcset=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/666.jpg 600w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/666-240x300.jpg 240w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"750\" data-id=\"1521\" src=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/777.jpg\" alt=\"\" class=\"wp-image-1521\" srcset=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/777.jpg 600w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/777-240x300.jpg 240w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"750\" data-id=\"1522\" src=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/888.jpg\" alt=\"\" class=\"wp-image-1522\" srcset=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/888.jpg 600w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/888-240x300.jpg 240w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"750\" data-id=\"1523\" src=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/999.jpg\" alt=\"\" class=\"wp-image-1523\" srcset=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/999.jpg 600w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2026\/01\/999-240x300.jpg 240w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En esta oportunidad, es el turno de los emprenddimientos gastron\u00f3micos, tanto locales como de otras localidades, que aportaron sabor, aroma y ese toque especial que hizo de esta feria una verdadera experiencia para todos los sentidos. Comidas, tragos y bebidas formaron parte de una propuesta variada y de gran calidad, que acompa\u00f1\u00f3 una jornada donde&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1520,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/1514"}],"collection":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=1514"}],"version-history":[{"count":4,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/1514\/revisions"}],"predecessor-version":[{"id":1529,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/1514\/revisions\/1529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/1520"}],"wp:attachment":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=1514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=1514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=1514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}