{"id":1072,"date":"2025-06-06T15:23:47","date_gmt":"2025-06-06T18:23:47","guid":{"rendered":"https:\/\/morrison.gob.ar\/?p=1072"},"modified":"2025-06-06T15:23:47","modified_gmt":"2025-06-06T18:23:47","slug":"morrison-se-suma-a-la-maraton-del-sudeste-con-una-eco-feria-y-maraton-de-reciclado","status":"publish","type":"post","link":"https:\/\/morrison.gob.ar\/index.php\/2025\/06\/06\/morrison-se-suma-a-la-maraton-del-sudeste-con-una-eco-feria-y-maraton-de-reciclado\/","title":{"rendered":"Morrison se suma a la Marat\u00f3n del Sudeste con una Eco Feria y Marat\u00f3n de Reciclado"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Este <strong>domingo 8 de junio<\/strong>, la ciudad de Morrison vivir\u00e1 una jornada cargada de actividad, conciencia ambiental y participaci\u00f3n comunitaria. En el marco de la <strong>Marat\u00f3n del Sudeste<\/strong>, la <strong>Municipalidad de Morrison<\/strong>, junto al <strong>Club de Emprendedores<\/strong>, organizan una <strong>Eco Feria<\/strong> y una original <strong>Marat\u00f3n de Reciclado<\/strong> en el <strong>Parque Municipal<\/strong> y la <strong>Peatonal San Mart\u00edn<\/strong>.<\/h3>\n\n\n\n<p>Desde las <strong>10:00 hs<\/strong>, se podr\u00e1 recorrer una <strong>feria de emprendedores y artesanos<\/strong> de Morrison y la regi\u00f3n, que ofrecer\u00e1n productos locales, artesanales y sustentables. La propuesta busca acompa\u00f1ar el evento deportivo con una experiencia cultural y ambiental que re\u00fana a vecinos y visitantes.<\/p>\n\n\n\n<p>A partir de las <strong>14:00 hs<\/strong>, la actividad se traslada a la <strong>Peatonal San Mart\u00edn<\/strong>, donde se realizar\u00e1 una <strong>Marat\u00f3n de Reciclado<\/strong> con <strong>sorteos y premios<\/strong> para quienes acerquen <strong>cart\u00f3n o pl\u00e1stico reciclable<\/strong>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cCuanto m\u00e1s recicl\u00e1s, m\u00e1s chances ten\u00e9s de ganar\u201d, destacan desde la organizaci\u00f3n.<\/p>\n<\/blockquote>\n\n\n\n<p>Adem\u00e1s, habr\u00e1 un <strong>show musical infantil<\/strong> a cargo del grupo <strong>Piedra, Papel, Tijera<\/strong>, pensado especialmente para las infancias y con un fuerte mensaje de <strong>conciencia ecol\u00f3gica y cuidado del ambiente<\/strong>.<\/p>\n\n\n\n<p>La propuesta, impulsada por el <strong>Club de Emprendedores<\/strong> y acompa\u00f1ada por el municipio, combina deporte, cultura, reciclaje y educaci\u00f3n ambiental, consolidando a Morrison como una ciudad comprometida con el desarrollo sustentable.<\/p>\n\n\n\n<p>\ud83d\udccd <strong>Organiza<\/strong>: Club de Emprendedores<br>\ud83d\udccd <strong>Invita<\/strong>: Municipalidad de Morrison<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/06\/eco-feria-junio-flayer-819x1024.jpeg\" alt=\"\" class=\"wp-image-1073\" style=\"width:600px\" srcset=\"https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/06\/eco-feria-junio-flayer-819x1024.jpeg 819w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/06\/eco-feria-junio-flayer-240x300.jpeg 240w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/06\/eco-feria-junio-flayer-768x960.jpeg 768w, https:\/\/morrison.gob.ar\/wp-content\/uploads\/2025\/06\/eco-feria-junio-flayer.jpeg 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure><\/div>","protected":false},"excerpt":{"rendered":"<p>Este domingo 8 de junio, la ciudad de Morrison vivir\u00e1 una jornada cargada de actividad, conciencia ambiental y participaci\u00f3n comunitaria. En el marco de la Marat\u00f3n del Sudeste, la Municipalidad de Morrison, junto al Club de Emprendedores, organizan una Eco Feria y una original Marat\u00f3n de Reciclado en el Parque Municipal y la Peatonal San&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1074,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/1072"}],"collection":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=1072"}],"version-history":[{"count":1,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/1072\/revisions"}],"predecessor-version":[{"id":1075,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/1072\/revisions\/1075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/1074"}],"wp:attachment":[{"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=1072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=1072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/morrison.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=1072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}